{"id":10,"count":11,"description":"July 2020","link":"https:\/\/fluxo.si\/en\/secao\/newsletter\/39\/","name":"Newsletter 39","slug":"39","taxonomy":"category","parent":1,"meta":[],"acf":{"introducao":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Newsletter 39 - Fluxo Solu\u00e7\u00f5es<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluxo.si\/en\/secao\/newsletter\/39\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Newsletter 39 - Fluxo Solu\u00e7\u00f5es\" \/>\n<meta property=\"og:description\" content=\"Julho 2020\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluxo.si\/en\/secao\/newsletter\/39\/\" \/>\n<meta property=\"og:site_name\" content=\"Fluxo Solu\u00e7\u00f5es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fluxo.si\\\/en\\\/secao\\\/newsletter\\\/39\\\/\",\"url\":\"https:\\\/\\\/fluxo.si\\\/en\\\/secao\\\/newsletter\\\/39\\\/\",\"name\":\"Arquivos Newsletter 39 - Fluxo Solu\u00e7\u00f5es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluxo.si\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluxo.si\\\/en\\\/secao\\\/newsletter\\\/39\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluxo.si\\\/en\\\/secao\\\/newsletter\\\/39\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fluxo.si\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edticas\",\"item\":\"https:\\\/\\\/fluxo.si\\\/en\\\/secao\\\/newsletter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsletter 39\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluxo.si\\\/#website\",\"url\":\"https:\\\/\\\/fluxo.si\\\/\",\"name\":\"Fluxo Solu\u00e7\u00f5es\",\"description\":\"Solu\u00e7\u00f5es e servi\u00e7os para processos industriais de produ\u00e7\u00e3o, movimenta\u00e7\u00e3o e armazenagem de fluidos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/fluxo.si\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluxo.si\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fluxo.si\\\/#organization\",\"name\":\"Fluxo Solu\u00e7\u00f5es Integradas\",\"url\":\"https:\\\/\\\/fluxo.si\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fluxo.si\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fluxo.si\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/logo-fluxo-800.png\",\"contentUrl\":\"https:\\\/\\\/fluxo.si\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/logo-fluxo-800.png\",\"width\":800,\"height\":268,\"caption\":\"Fluxo Solu\u00e7\u00f5es Integradas\"},\"image\":{\"@id\":\"https:\\\/\\\/fluxo.si\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fluxosolutions\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Newsletter 39 - Fluxo Solu\u00e7\u00f5es","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluxo.si\/en\/secao\/newsletter\/39\/","og_locale":"en_US","og_type":"article","og_title":"Arquivos Newsletter 39 - Fluxo Solu\u00e7\u00f5es","og_description":"Julho 2020","og_url":"https:\/\/fluxo.si\/en\/secao\/newsletter\/39\/","og_site_name":"Fluxo Solu\u00e7\u00f5es","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fluxo.si\/en\/secao\/newsletter\/39\/","url":"https:\/\/fluxo.si\/en\/secao\/newsletter\/39\/","name":"Newsletter Archives 39 - Fluxo Solutions","isPartOf":{"@id":"https:\/\/fluxo.si\/#website"},"breadcrumb":{"@id":"https:\/\/fluxo.si\/en\/secao\/newsletter\/39\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/fluxo.si\/en\/secao\/newsletter\/39\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fluxo.si\/"},{"@type":"ListItem","position":2,"name":"Not\u00edticas","item":"https:\/\/fluxo.si\/en\/secao\/newsletter\/"},{"@type":"ListItem","position":3,"name":"Newsletter 39"}]},{"@type":"WebSite","@id":"https:\/\/fluxo.si\/#website","url":"https:\/\/fluxo.si\/","name":"Flow Solutions","description":"Solutions and services for industrial processes of production, movement and storage of fluids.","publisher":{"@id":"https:\/\/fluxo.si\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluxo.si\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fluxo.si\/#organization","name":"Integrated Solutions Flow","url":"https:\/\/fluxo.si\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fluxo.si\/#\/schema\/logo\/image\/","url":"https:\/\/fluxo.si\/wp-content\/uploads\/2021\/05\/logo-fluxo-800.png","contentUrl":"https:\/\/fluxo.si\/wp-content\/uploads\/2021\/05\/logo-fluxo-800.png","width":800,"height":268,"caption":"Fluxo Solu\u00e7\u00f5es Integradas"},"image":{"@id":"https:\/\/fluxo.si\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/fluxosolutions\/"]}]}},"_links":{"self":[{"href":"https:\/\/fluxo.si\/en\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluxo.si\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/fluxo.si\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/fluxo.si\/en\/wp-json\/wp\/v2\/categories\/1"}],"wp:post_type":[{"href":"https:\/\/fluxo.si\/en\/wp-json\/wp\/v2\/posts?categories=10"},{"href":"https:\/\/fluxo.si\/en\/wp-json\/wp\/v2\/produto?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}